{"id":14723,"date":"2022-02-23T19:07:26","date_gmt":"2022-02-23T18:07:26","guid":{"rendered":"https:\/\/liceoaprilia.edu.it\/?p=14723"},"modified":"2022-02-23T19:07:26","modified_gmt":"2022-02-23T18:07:26","slug":"sofia-goggia-dallinfortunio-alla-medaglia-dargento","status":"publish","type":"post","link":"https:\/\/liceoaprilia.edu.it\/2022\/02\/23\/sofia-goggia-dallinfortunio-alla-medaglia-dargento\/","title":{"rendered":"Sofia Goggia: dall\u2019infortunio alla medaglia d\u2019argento"},"content":{"rendered":"\r\n\r\n\r\n<h2 id=\"simbolo-della-resilienza-sofia-goggia-stupisce-tu-alle-olimpiadi-invernali-di-pechino\">Simbolo della resilienza, Sofia Goggia stupisce tu alle Olimpiadi Invernali di Pechino<\/h2>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/www.nicoladagostino.com\/wp-content\/uploads\/2022\/02\/OIF.jpeg\" alt=\"\" class=\"wp-image-639\"\/><\/figure>\r\n\r\n\r\n\r\n<p>Sofia Goggia, sciatrice alpina italiana, dopo un infortunio avvenuto a Corna, \u00e8 riuscita a salire sul podio delle Olimpiadi Invernali di Pechino vincendo la medaglia d\u2019argento nella specialit\u00e0 della discesa libera femminile.<\/p>\r\n\r\n\r\n\r\n<p>Il 23 gennaio, solo poche semane fa, a Corna D\u2019Ampezzo, cadendo, aveva subito un infortunio che le aveva causato una microfraura del perone e la roura del legamento crociato sinistro.<\/p>\r\n\r\n\r\n\r\n<p>Dopo l\u2019incidente aveva dichiarato di voler comunque partecipare alle Olimpiadi e ha preferito iniziare un percorso di riabilitazione invece di eseguire un\u2019operazione, che avrebbe reso la guarigione pi\u00f9 lunga. Dopo diverse sedute di fisioterapia l\u2019atleta \u00e8 arrivata a Pechino dove ha provato le piste. A causa di un\u2019altra caduta ha deciso di non prendere parte alla gara del Super Gigante per non rischiare di compromettere la discesa libera.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/www.nicoladagostino.com\/wp-content\/uploads\/2022\/02\/Sofia-Goggia-ANSA-22-2-2022-1024x658-1.jpeg\" alt=\"\" class=\"wp-image-640\"\/><\/figure>\r\n\r\n\r\n\r\n<p>Il 15 febbraio era pronta per partecipare alla gara, dove al contrario delle sue aspettative ha vinto l&#8217;argento, con solo 16 centesimi di secondo di differenza con la prima classificata svizzera Souter Corinne.<\/p>\r\n\r\n\r\n\r\n<p>Sofia Goggia ha poi dichiarato a \u201cla Repubblica\u201d di essersi senta \u201cispirata da una luce\u201d e che \u00e8 stato proprio il sogno olimpico a farla guarire pi\u00f9 in fretta.<\/p>\r\n\r\n\r\n\r\n<p>Con questo evento lo sport ha fatto vedere quanto possa essere imprevedibile e sorprendente Sofia Goggia. <\/p>\r\n\r\n\r\n\r\n<p>E<em>lettra Valenza 3E<\/em><\/p>\r\n\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>Simbolo della resilienza, Sofia Goggia stupisce tu alle Olimpiadi Invernali di Pechino Sofia Goggia, sciatrice alpina italiana, dopo un infortunio avvenuto a Corna, \u00e8 riuscita a salire sul podio delle Olimpiadi Invernali di Pechino vincendo la medaglia d\u2019argento nella specialit\u00e0 della discesa libera femminile. Il 23 gennaio, solo poche semane fa, a Corna D\u2019Ampezzo, cadendo, aveva subito un infortunio che le aveva causato una microfraura del perone e la roura del legamento crociato sinistro. Dopo l\u2019incidente aveva dichiarato di voler comunque partecipare alle Olimpiadi e ha preferito iniziare un percorso di riabilitazione invece di eseguire un\u2019operazione, che avrebbe reso la guarigione pi\u00f9 lunga. Dopo diverse sedute di fisioterapia l\u2019atleta \u00e8 arrivata a Pechino dove ha provato le piste. A causa di un\u2019altra caduta ha deciso di non prendere parte alla gara del Super Gigante per non rischiare di compromettere la discesa libera. Il 15 febbraio era pronta per partecipare alla gara, dove al contrario delle sue aspettative ha vinto l&#8217;argento, con solo 16 centesimi di secondo di differenza con la prima classificata svizzera Souter Corinne. Sofia Goggia ha poi dichiarato a \u201cla Repubblica\u201d di essersi senta \u201cispirata da una luce\u201d e che \u00e8 stato proprio il sogno olimpico a farla guarire pi\u00f9 in fretta. Con questo evento lo sport ha fatto vedere quanto possa essere imprevedibile e sorprendente Sofia Goggia. Elettra Valenza 3E<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16,23,24],"tags":[],"_links":{"self":[{"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/posts\/14723"}],"collection":[{"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/comments?post=14723"}],"version-history":[{"count":1,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/posts\/14723\/revisions"}],"predecessor-version":[{"id":14724,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/posts\/14723\/revisions\/14724"}],"wp:attachment":[{"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/media?parent=14723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/categories?post=14723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/tags?post=14723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}