{"id":2631,"date":"2019-10-25T08:38:04","date_gmt":"2019-10-25T06:38:04","guid":{"rendered":"https:\/\/wp.liceoaprilia.edu.it\/?p=2631"},"modified":"2019-10-25T08:38:04","modified_gmt":"2019-10-25T06:38:04","slug":"iscrizione-al-laboratorio-musicale-a-s-19-20","status":"publish","type":"post","link":"https:\/\/liceoaprilia.edu.it\/2019\/10\/25\/iscrizione-al-laboratorio-musicale-a-s-19-20\/","title":{"rendered":"Iscrizione al Laboratorio Musicale a.s. 19-20"},"content":{"rendered":"<div><span style=\"font-size: small;\">Gli alunni del Liceo che vogliono partecipare al laboratorio devono compilare il modulo reperibile al link \u00a0 <a href=\"https:\/\/forms.gle\/3buSv4ZFTAcUGU6V9\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\"> https:\/\/forms.gle\/3buSv4ZFTAcUGU6V9<\/a>\u00a0 entro il 9 Novembre 2019.<\/span><\/div>\n<div>\n<p class=\"x_MsoNormal\"><span style=\"font-size: small;\">Si precisa che durante il laboratorio NON si terranno lezioni di musica, in quanto si richiede ai partecipanti di avere gi\u00e0 una buona pratica del proprio strumento.<\/span><\/p>\n<p class=\"x_MsoNormal\"><span style=\"font-size: small;\">\u00a0<\/span><span style=\"font-size: small;\">La convocazione per il primo incontro, dove verranno esplicitate le finalit\u00e0 del laboratorio, verr\u00e0 inoltrata ai partecipanti tramite email.<\/span><\/p>\n<p><span style=\"font-size: small;\">La partecipazione al laboratorio \u00e8 gratuita.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gli alunni del Liceo che vogliono partecipare al laboratorio devono compilare il modulo reperibile al link \u00a0 https:\/\/forms.gle\/3buSv4ZFTAcUGU6V9\u00a0 entro il 9 Novembre 2019. Si precisa che durante il laboratorio NON si terranno lezioni di musica, in quanto si richiede ai partecipanti di avere gi\u00e0 una buona pratica del proprio strumento. \u00a0La convocazione per il primo incontro, dove verranno esplicitate le finalit\u00e0 del laboratorio, verr\u00e0 inoltrata ai partecipanti tramite email. La partecipazione al laboratorio \u00e8 gratuita.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/posts\/2631"}],"collection":[{"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/comments?post=2631"}],"version-history":[{"count":1,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/posts\/2631\/revisions"}],"predecessor-version":[{"id":2632,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/posts\/2631\/revisions\/2632"}],"wp:attachment":[{"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/media?parent=2631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/categories?post=2631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/liceoaprilia.edu.it\/wp-json\/wp\/v2\/tags?post=2631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}